{"id":75171,"date":"2018-03-07T09:57:39","date_gmt":"2018-03-07T00:57:39","guid":{"rendered":"https:\/\/www.asreet.com\/osaka\/?post_type=shop_free&#038;p=75171"},"modified":"2026-08-06T15:24:23","modified_gmt":"2026-08-06T06:24:23","slug":"75171","status":"publish","type":"shop_free","link":"https:\/\/www.asreet.com\/osaka\/shop_free\/data\/75171","title":{"rendered":"EXECUTIVE7"},"menu_order":0,"template":"","format":"standard","tags":[],"city":[61],"acf":[],"_links":{"self":[{"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/shop_free\/75171"}],"collection":[{"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/shop_free"}],"about":[{"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/types\/shop_free"}],"version-history":[{"count":1,"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/shop_free\/75171\/revisions"}],"predecessor-version":[{"id":203578,"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/shop_free\/75171\/revisions\/203578"}],"wp:attachment":[{"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/media?parent=75171"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/tags?post=75171"},{"taxonomy":"city","embeddable":true,"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/city?post=75171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}