{"id":99535,"date":"2022-05-06T17:07:04","date_gmt":"2022-05-06T08:07:04","guid":{"rendered":"https:\/\/www.asreet.com\/osaka\/?post_type=shop_free&#038;p=99535"},"modified":"2026-08-07T15:53:38","modified_gmt":"2026-08-07T06:53:38","slug":"99535","status":"publish","type":"shop_free","link":"https:\/\/www.asreet.com\/osaka\/shop_free\/data\/99535","title":{"rendered":"\u30a8\u30cb\u30bf\u30a4\u30e0\u30d5\u30a3\u30c3\u30c8\u30cd\u30b9\u671d\u65e5\u304c\u4e18\u5e97"},"menu_order":0,"template":"","format":"standard","tags":[244],"city":[49],"acf":[],"_links":{"self":[{"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/shop_free\/99535"}],"collection":[{"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/shop_free"}],"about":[{"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/types\/shop_free"}],"version-history":[{"count":1,"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/shop_free\/99535\/revisions"}],"predecessor-version":[{"id":208212,"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/shop_free\/99535\/revisions\/208212"}],"wp:attachment":[{"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/media?parent=99535"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/tags?post=99535"},{"taxonomy":"city","embeddable":true,"href":"https:\/\/www.asreet.com\/osaka\/wp-json\/wp\/v2\/city?post=99535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}